{"id":1562,"date":"2021-03-17T20:55:47","date_gmt":"2021-03-17T19:55:47","guid":{"rendered":"http:\/\/merle-buehrer.de\/gs\/?p=1562"},"modified":"2021-03-17T20:55:49","modified_gmt":"2021-03-17T19:55:49","slug":"ripple-salaedle-guerkle","status":"publish","type":"post","link":"https:\/\/merle-buehrer.de\/gs\/2021\/03\/17\/ripple-salaedle-guerkle\/","title":{"rendered":"Ripple, Sal\u00e4dle, G\u00fcrkle"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Es gibt immer wieder Situationen, bei denen ich mich auch nach langer Zeit hier im Norden noch ein bisschen verloren f\u00fchle. Zum Beispiel, wenn niemand wei\u00df, was \u00aba Ripple\u00bb sein soll und dann auch der Zusatz \u00abzum Vesper\u00bb nicht recht weiterhilft. In dem Fall hilft nur Selber-P\u00f6keln, ein Wei\u00dfbier \u00f6ffnen und dem S\u00fcden zuprosten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">K\u00fcchentagebuch, Mittwoch 17. M\u00e4rz 2021<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Badisches Ripple, gep\u00f6kelt und gekocht (ich hab den Link verschmissen, aber so \u00e4hnlich wie <a rel=\"noreferrer noopener\" href=\"https:\/\/rezepte247.com\/2019\/01\/06\/rippchen-selber-poekeln\/\" target=\"_blank\">Hier<\/a>, und nur etwa \u00bdh bei 80\u00b0 erw\u00e4rmen)<\/li><li>Kartoffelsalat, Essiggurke, Senf, Tomaten<\/li><li>Brezeln, Wei\u00dfbier<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/03\/ripple.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/03\/ripple-768x1024.jpg\" alt=\"\" class=\"wp-image-1563\" srcset=\"https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/03\/ripple-768x1024.jpg 768w, https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/03\/ripple-225x300.jpg 225w, https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/03\/ripple-1152x1536.jpg 1152w, https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/03\/ripple.jpg 1512w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><figcaption>Gep\u00f6keltes Vesper-Ripple<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt immer wieder Situationen, bei denen ich mich auch nach langer Zeit hier im Norden noch ein bisschen verloren f\u00fchle. Zum Beispiel, wenn niemand wei\u00df, was \u00aba Ripple\u00bb sein soll und dann auch der Zusatz \u00abzum Vesper\u00bb nicht recht weiterhilft. In dem Fall hilft nur Selber-P\u00f6keln, ein Wei\u00dfbier \u00f6ffnen und dem S\u00fcden zuprosten. K\u00fcchentagebuch, &#8230; <a title=\"Ripple, Sal\u00e4dle, G\u00fcrkle\" class=\"read-more\" href=\"https:\/\/merle-buehrer.de\/gs\/2021\/03\/17\/ripple-salaedle-guerkle\/\" aria-label=\"Mehr Informationen \u00fcber Ripple, Sal\u00e4dle, G\u00fcrkle\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":1563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47,35],"tags":[],"class_list":["post-1562","post","type-post","status-publish","format-standard","hentry","category-schwabisch","category-schwein"],"_links":{"self":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts\/1562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/comments?post=1562"}],"version-history":[{"count":1,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts\/1562\/revisions"}],"predecessor-version":[{"id":1564,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts\/1562\/revisions\/1564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/media\/1563"}],"wp:attachment":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/media?parent=1562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/categories?post=1562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/tags?post=1562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}