{"id":2924,"date":"2021-09-04T20:48:33","date_gmt":"2021-09-04T18:48:33","guid":{"rendered":"http:\/\/merle-buehrer.de\/gs\/?p=2924"},"modified":"2021-09-04T20:48:35","modified_gmt":"2021-09-04T18:48:35","slug":"bohnen-kokosmilch-reis","status":"publish","type":"post","link":"https:\/\/merle-buehrer.de\/gs\/2021\/09\/04\/bohnen-kokosmilch-reis\/","title":{"rendered":"Bohnen, Kokosmilch, Reis"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Ein Bekannter, der im Internet auf diesen Blog gesto\u00dfen ist (was Menschen nicht alles in ihrer Freizeit treiben!) hat mich gelobt. Jetzt bin ich auf keinen Fall unempfindlich gegen\u00fcber Lob, nur her damit! Aber dieses Lob ging sinngem\u00e4\u00df in die Richtung: Du bist auf dem richtigen Weg, wenig Fleisch, das ist gut f\u00fcr die Tiere, f\u00fcr die Natur und f\u00fcr deine Gesundheit. Mach weiter so!  &#8211; Das muss ich zurechtr\u00fccken, so ist das n\u00e4mlich nicht. Wenn ich mir das so anschaue, dann ist es schon richtig, dass das K\u00fcchentagebuch recht Gem\u00fcse-lastig ist. Aber das hat den einfachen Grund, dass mir u.a. Herr Ottolenghi eine Welt er\u00f6ffnet hat, in der es um Geschmack geht, um \u00fcberraschende Kombinationen von Gew\u00fcrzen und Lebensmitteln und um mir unbekannte Zubereitungsarten, und es ist einfach leichter, mit mich Gem\u00fcse zu \u00fcberraschen als mit einem Steak (obwohl <a rel=\"noreferrer noopener\" href=\"https:\/\/merle-buehrer.de\/gs\/2021\/07\/24\/filet-asia-marinade-sous-vide\/\" data-type=\"post\" data-id=\"2594\" target=\"_blank\">auch das geht<\/a>). Aber dass Fleisch-b\u00f6se\/Pflanze-gut und all der Quatsch viel zu kurz gegriffen ist, sieht sieht man zum Beispiel daran, dass die spanische Lagune Mar Menor, die gerade abkackt, von <strong>Gem\u00fcse<\/strong>bauern vergiftet wurde. Dass wegen dem Avocado-Hype von Gro\u00dfstadt-Hipstern ganze Regionen abgeforstet wurden und das letzte bisschen Wasser der Gegend f\u00fcr die Plantagen vergeudet wurde, damit man seine Avocado bei Aldi f\u00fcr einsfuffzig kaufen kann. Ich hab leider keine L\u00f6sung f\u00fcr das Problem der Massentierhaltung, au\u00dfer vielleicht den zynischen Tipp, beim &#8222;Bauern um die Ecke&#8220; einzukaufen. Wenn aber jemand denkt, dass das bei der Massen-Pflanzen-Haltung anders wird, der irrt gewaltig. Wollte ich nur mal klarstellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">K\u00fcchentagebuch, Samstag 4. September 2021<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Bihari-Masala mit gr\u00fcnen Bohnen (<a href=\"https:\/\/www.ankegroener.de\/blog\/?p=12953\" target=\"_blank\" rel=\"noreferrer noopener\">ankegroener<\/a>) &#8211; jede Bohne einzeln gestreichelt und gro\u00dfgezogen, angebunden zwar, aber irgendwie auch freilaufend<\/li><li>Reis<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/09\/bohnenmasala.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"756\" height=\"1008\" src=\"https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/09\/bohnenmasala.jpg\" alt=\"\" class=\"wp-image-2926\" srcset=\"https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/09\/bohnenmasala.jpg 756w, https:\/\/merle-buehrer.de\/gs\/wp-content\/uploads\/2021\/09\/bohnenmasala-225x300.jpg 225w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/><\/a><figcaption>Wir haben eindeutig zu viele Bohnen, aber so zubereitet ist das gar nicht schlimm<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ein Bekannter, der im Internet auf diesen Blog gesto\u00dfen ist (was Menschen nicht alles in ihrer Freizeit treiben!) hat mich gelobt. Jetzt bin ich auf keinen Fall unempfindlich gegen\u00fcber Lob, nur her damit! Aber dieses Lob ging sinngem\u00e4\u00df in die Richtung: Du bist auf dem richtigen Weg, wenig Fleisch, das ist gut f\u00fcr die Tiere, &#8230; <a title=\"Bohnen, Kokosmilch, Reis\" class=\"read-more\" href=\"https:\/\/merle-buehrer.de\/gs\/2021\/09\/04\/bohnen-kokosmilch-reis\/\" aria-label=\"Mehr Informationen \u00fcber Bohnen, Kokosmilch, Reis\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":2926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2924","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts\/2924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/comments?post=2924"}],"version-history":[{"count":3,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts\/2924\/revisions"}],"predecessor-version":[{"id":2928,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/posts\/2924\/revisions\/2928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/media\/2926"}],"wp:attachment":[{"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/media?parent=2924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/categories?post=2924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/merle-buehrer.de\/gs\/wp-json\/wp\/v2\/tags?post=2924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}